{"id":6044,"date":"2018-10-10T00:00:00","date_gmt":"2018-10-09T22:00:00","guid":{"rendered":"https:\/\/cri.it\/sicilia\/2018\/10\/10\/aci-catena-ct-al-trinacria-camp-2018-vince-la-gioventu\/"},"modified":"2018-10-10T00:00:00","modified_gmt":"2018-10-09T22:00:00","slug":"aci-catena-ct-al-trinacria-camp-2018-vince-la-gioventu","status":"publish","type":"post","link":"https:\/\/cri.it\/sicilia\/2018\/10\/10\/aci-catena-ct-al-trinacria-camp-2018-vince-la-gioventu\/","title":{"rendered":"Aci Catena (CT) \u2013 Al &#8220;TrinaCRIa Camp 2018&#8221; vince la Giovent\u00f9"},"content":{"rendered":"<h1 class=\"viewTitolo viewTitolo1\">Aci Catena (CT) &ndash; Al &quot;TrinaCRIa Camp 2018&quot; vince la Giovent&ugrave;<\/h1>\n<h2 class=\"viewSottotitolo viewTitolo2\">Grande successo del Campo Regionale per &quot;Corso Istruttori delle attivit&agrave; rivolte ai Giovani&quot;<\/h2>\n<div class='viewLineBreak'>&nbsp;<\/div>\n<div class='viewPar BLOBAlignJustify'>\n<p >Si \u00e8 concluso con successo il <strong class='userFormat1'>&#8220;TrinaCRIa Camp 2018&#8221;, il Campo Regionale di formazione per &#8220;Corso Istruttori delle attivit\u00e0 rivolte alla Giovent\u00f9&#8221;<\/strong>, svoltosi presso la scuola Santa Lucia di Aci Catena dal 2 al 5 agosto 2018.<\/p>\n<p>Quattro giorni intensi che hanno portato alla formazione di Istruttori rispettivamente di: Educazione alla Pace, promozione della Salute, Giovani in Azione e Riduzione dei rischi da disastro e adattamento ai cambiamenti climatici. Contestualmente al Campo, si \u00e8 svolta la riunione della squadra nazionale del Vicepresidente nazionale Gabriele Bellocchi che ha scelto la calda isola siciliana per i propri lavori in vista dei tanti appuntamenti in programma per i prossimi mesi per i giovani della Croce Rossa.<\/p>\n<p><\/p>\n<\/div>\n<div class='viewLineBreak'>&nbsp;<\/div>\n<div class='BLOBWidth100'>\n<div class='BLOBFloatRight BLOBIMGSpacerLeft'><img fetchpriority=\"high\" id='img-178' src='https:\/\/cri.it\/wp-content\/uploads\/cri-content\/images\/8\/b\/1\/D.c4db3ffdfac5f0411dce\/WhatsApp_Image_2018_10_08_at_23.51.15.jpeg' width=\"666\" height=\"500\" alt='TrinaCRIa Camp 2018' \/><\/div>\n<div class='viewParCell BLOBAlignJustify'>\n<p>Il Campo, previsto per 70 partecipanti, \u00e8 stato allestito con aree idonee alla refezione e all&#8217;alloggio, cinque aule didattiche e un&#8217;aula per l&#8217;attivit\u00e0 plenaria. L&#8217;organizzazione dei corsi \u00e8 stata sicuramente innovativa con i corsisti, provenienti da 15 comitati della Sicilia, divisi in classi miste, secondo un criterio territoriale e non di specificit\u00e0 di corso.&nbsp;<\/p>\n<p>La grande novit\u00e0 del TrinaCRIa Camp 2018 \u00e8 stato <strong class='userFormat1'>il programma del corso per Istruttori Giovani in Azione (G. I. A.)<\/strong>. Infatti, sotto la supervisione della squadra nazionale delle attivit\u00e0 rivolte alla Giovent\u00f9, guidata da Bellocchi, e grazie alla presenza di due formatori esterni indicati dal Comitato Nazionale, \u00e8 stato sperimentato un nuovo programma incentrato sulla <strong class='userFormat1'>promozione del volontariato<\/strong> e della <strong class='userFormat1'>cittadinanza attiva<\/strong>, nonch\u00e9 su attivit\u00e0 attuali ed in crescita quali l&#8217;<strong class='userFormat1'>alternanza scuola-lavoro<\/strong>, il <strong class='userFormat1'>bando per il servizio civile<\/strong> ed i <strong class='userFormat1'>progetti &#8220;8-13&#8221;<\/strong> ed <strong class='userFormat1'>&#8220;Anche io posso&#8221;<\/strong>.<\/p>\n<p><\/p>\n<\/div>\n<div class='BLOBFloatClear BLOBRow1px'>&nbsp;<\/div>\n<\/div>\n<div class='BLOBWidth100'>\n<div class='BLOBFloatRight BLOBIMGSpacerLeft'><img id='img-179' src='https:\/\/cri.it\/wp-content\/uploads\/cri-content\/images\/1\/6\/d\/D.f9425d4ff36d3c49846c\/WhatsApp_Image_2018_10_08_at_23.51.15__1_.jpeg' width=\"700\" height=\"393\" alt='TrinaCRIa Camp 2018' \/><\/div>\n<div class='viewParCell BLOBAlignJustify'>\n<p>In generale, il Campo \u00e8 stato articolato in due parti di cui una dedicata alle sessioni comuni alle quattro tipologie di Istruttori ed una parte specifica per ogni tematica. Solo per le parti specifiche la divisione in gruppi \u00e8 stata per tipologia di corso. Tanti gli argomenti affrontati attraverso lezioni interattive ed attivit\u00e0, dalla progettazione,advocacy, dinamiche di gruppo, principi e valori, alla gestione d&#8217;aula, comunicazione, valutazione e tanto altro ancora.&nbsp;<\/p>\n<p>&#8220;<em class='userFormat2'>TrinaCRIa, un nome simbolico per ricordare le nostre origini, il legame con la nostra isola e con la nostra <acronym title='Croce Rossa Italiana' lang='it'>CRI<\/acronym>. E non solo! Il Comitato di Palermo<\/em>&nbsp;&#8211;&nbsp; ricorda Erica Milone, Coordinatore Regionale delle attivit\u00e0 rivolte alla Giovent\u00f9 della <acronym title='Croce Rossa Italiana' lang='it'>CRI<\/acronym> Sicilia &#8211;&nbsp;<em class='userFormat2'>nel 2014 ha ospitato il primo TrinaCRIa Camp, organizzato dall&#8217;allora Delegato Tecnico Regionale O.S.5 Bellocchi, durante il quale \u00e8 stata realizzata la prima sperimentazione del corso &#8220;Leader&#8221;, poi evolutosi nell&#8217;attuale Giovani in Azione. Cos\u00ec come il 2014, il TrinaCRIa 2018 si \u00e8 distinto per il suo carattere innovativo e per la volont\u00e0 di provare nuove soluzioni per rendere pi\u00f9 funzionale ed efficace la nostra formazione. Per questo<\/em>&nbsp;&#8211; prosegue Erica Milone &#8211;&nbsp;<em class='userFormat2'>ringrazio tutti i formatori che si sono imbarcati in questa avventura impegnandosi al 100%, lo staff nazionale che ci ha sostenuti costantemente durante il percorso, lo staff logistico del campo e i volontari di Aci Catena efficienti ed instancabili, il Presidente regionale Corsaro e tutto lo staff regionale che ci ha permesso di dar vita a questo grande evento. Ma soprattutto, ringrazio tutti i corsisti e i Presidenti dei Comitati della Sicilia che continuano a credere in questo ambizioso lavoro, mettendosi in gioco e contribuendo attivamente a questo grande risultato. Come ho detto alla chiusura del TrinaCRIa Camp 2018,<\/em>&nbsp;&#8211; conclude Erica &#8211;&nbsp;<em class='userFormat2'>questa per la giovent\u00f9 siciliana era una grande sfida, e credo di poter dire, con molta sicurezza, che l&#8217;abbiamo vinta!<\/em>&#8220;.&nbsp;<\/p>\n<p><\/p>\n<\/div>\n<div class='BLOBFloatClear BLOBRow1px'>&nbsp;<\/div>\n<\/div>\n<div class='viewLineBreak'>&nbsp;<\/div>\n<div class='BLOBBlockAlignLeft'><img id='img-180' src='https:\/\/cri.it\/wp-content\/uploads\/cri-content\/images\/6\/e\/1\/D.515ed1661d92a1dd5b5b\/WhatsApp_Image_2018_10_08_at_23.51.17.jpeg' width=\"666\" height=\"500\" alt='TrinaCRIa Camp 2018' class='viewImg' \/><\/div>\n<div class='BLOBFloatClear'><\/div>\n<div class='viewLineBreak'>&nbsp;<\/div>\n<div>\n<hr class='viewHR BLOBAlignLeft' \/><\/div>\n<div class='viewPar BLOBAlignJustify'>\n<p ><em class='userFormat2'>di Irene Cimino, volontaria della <acronym title='Croce Rossa Italiana' lang='it'>CRI<\/acronym> di Castelvetrano<\/em><br \/><em class='userFormat2'>Croce Rossa Italiana \u2013 Comitato Regionale della Sicilia<\/em><br \/><em class='userFormat2'>Staff Regionale Obiettivo 6 &#8211; &#8220;Sviluppo, comunicazione e promozione del volontariato\u201d<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Quattro giorni intensi che hanno portato alla formazione di Istruttori rispettivamente di: Educazione alla Pace, promozione della Salute, Giovani in Azione e Riduzione dei rischi da disastro e adattamento ai cambiamenti climatici. Contestualmente al Campo, si \u00e8 svolta la riunione della squadra nazionale del Vicepresidente nazionale Gabriele Bellocchi che ha scelto la calda isola siciliana per i propri lavori in vista dei tanti appuntamenti in programma per i prossimi mesi per i giovani della Croce Rossa.<\/p>\n","protected":false},"author":47,"featured_media":6045,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[3,10,4,7,8,5],"tags":[],"class_list":["post-6044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comitato-sicilia","category-giovani","category-news","category-primo-piano-generico","category-primo-piano-attivita","category-secondo-piano-generico"],"interactive":false,"_links":{"self":[{"href":"https:\/\/cri.it\/sicilia\/wp-json\/wp\/v2\/posts\/6044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cri.it\/sicilia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cri.it\/sicilia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cri.it\/sicilia\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/cri.it\/sicilia\/wp-json\/wp\/v2\/comments?post=6044"}],"version-history":[{"count":0,"href":"https:\/\/cri.it\/sicilia\/wp-json\/wp\/v2\/posts\/6044\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cri.it\/sicilia\/wp-json\/wp\/v2\/media\/6045"}],"wp:attachment":[{"href":"https:\/\/cri.it\/sicilia\/wp-json\/wp\/v2\/media?parent=6044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cri.it\/sicilia\/wp-json\/wp\/v2\/categories?post=6044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cri.it\/sicilia\/wp-json\/wp\/v2\/tags?post=6044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}